{"id":162,"date":"2020-08-19T06:19:39","date_gmt":"2020-08-19T06:19:39","guid":{"rendered":"https:\/\/woodsworthindustries.com\/index.php\/projects\/"},"modified":"2024-07-23T06:23:59","modified_gmt":"2024-07-23T06:23:59","slug":"portfolio","status":"publish","type":"page","link":"https:\/\/woodsworthindustries.com\/index.php\/portfolio\/","title":{"rendered":"Portfolio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"162\" class=\"elementor elementor-162\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7a08d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a7a08d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a92b7d3\" data-id=\"a92b7d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fca011e elementor-widget elementor-widget-heading\" data-id=\"fca011e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.3 - 28-05-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Modular Kitchen<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c75db03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c75db03\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29fc0b9\" data-id=\"29fc0b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db82a43 elementor-widget elementor-widget-qi_addons_for_elementor_image_slider\" data-id=\"db82a43\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-image-slider     qodef-col-num--1 qodef-qi-grid qodef-qi-swiper-container  qodef-navigation--inside      qodef-navigation--hover-move\" data-options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerView&quot;:&quot;1&quot;,&quot;spaceBetween&quot;:30,&quot;spaceBetweenTablet&quot;:30,&quot;spaceBetweenMobile&quot;:30,&quot;effect&quot;:&quot;slide&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;centeredSlides&quot;:false,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;outsideNavigation&quot;:&quot;no&quot;,&quot;outsidePagination&quot;:&quot;no&quot;,&quot;unique&quot;:537,&quot;partialValue&quot;:0,&quot;disablePartialValue&quot;:&quot;&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-1.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-1-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-1-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-1-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.46-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-1.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-1-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-1-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-1-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-1.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-1-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-1-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-1-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-2.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-2-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-2-1024x768.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-2-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-1024x768.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-1.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-1-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-1-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/d9f3eb44-02a0-4e12-a2c2-6a4f28f40251.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/d9f3eb44-02a0-4e12-a2c2-6a4f28f40251.jpg 576w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/d9f3eb44-02a0-4e12-a2c2-6a4f28f40251-169x300.jpg 169w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6286.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6286.jpg 640w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6286-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/0f47b9c1-ac34-4b00-9358-bbd859cc7dab.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/0f47b9c1-ac34-4b00-9358-bbd859cc7dab.jpg 1600w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/0f47b9c1-ac34-4b00-9358-bbd859cc7dab-300x225.jpg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/0f47b9c1-ac34-4b00-9358-bbd859cc7dab-1024x768.jpg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/0f47b9c1-ac34-4b00-9358-bbd859cc7dab-768x576.jpg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/0f47b9c1-ac34-4b00-9358-bbd859cc7dab-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/58.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/58.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/58-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11111111.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11111111.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11111111-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16161616.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16161616.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16161616-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10101010.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10101010.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10101010-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/191919.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/191919.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/191919-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104728.287.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104728.287.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104728.287-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104646.350.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104646.350.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104646.350-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/19.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/19.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/19-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9999.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9999.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9999-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/161616.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/161616.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/161616-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/121212.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/121212.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/121212-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1919.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1919.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1919-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1616.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1616.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1616-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1515.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1515.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1515-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1414.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1414.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1414-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1212.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1212.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1212-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1010.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1010.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1010-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/888.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/888.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/888-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/777.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/777.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/777-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/444.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/444.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/444-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/666.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/666.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/666-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/222.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/222.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/222-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/99.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/99.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/99-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/88.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/88.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/88-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/66.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/66.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/66-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/44.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/44.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/44-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/20.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/20.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/20-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/18.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/18.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/18-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/15.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/15.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/15-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/14.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/14.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/14-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/13.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/13.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/13-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/8.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/8-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/7.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/7-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/4.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/4-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/3.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/3-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/17171717.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/17171717.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/17171717-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/181818.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/181818.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/181818-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/141414.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/141414.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/141414-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/111111.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/111111.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/111111-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/101010.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/101010.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/101010-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1818.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1818.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1818-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1717.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1717.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1717-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1111.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1111.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1111-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/999.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/999.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/999-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/111.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/111.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/111-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/77.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/77.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/77-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/33.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/33.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/33-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/22.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/22.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/22-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/12.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/12.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/12-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/6.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/6-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\t<\/div>\n\t\t<div class=\"swiper-button-prev\"><i aria-hidden=\"true\" class=\"fas fa-arrow-circle-left\"><\/i><\/div>\n\t<div class=\"swiper-button-next\"><i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9db4712\" data-id=\"9db4712\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19a1ae1 elementor-widget elementor-widget-image\" data-id=\"19a1ae1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.3 - 28-05-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104728.287.png\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104728.287.png\" class=\"attachment-large size-large wp-image-841\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104728.287.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104728.287-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e14257 elementor-widget elementor-widget-image\" data-id=\"2e14257\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104646.350.png\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104646.350.png\" class=\"attachment-large size-large wp-image-840\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104646.350.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T104646.350-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b8edf1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b8edf1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fca0d09\" data-id=\"fca0d09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c1cb5a elementor-widget elementor-widget-heading\" data-id=\"9c1cb5a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Modular Unit<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f77c79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f77c79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2974371\" data-id=\"2974371\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aff5dd7 elementor-widget elementor-widget-qi_addons_for_elementor_image_slider\" data-id=\"aff5dd7\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-image-slider     qodef-col-num--1 qodef-qi-grid qodef-qi-swiper-container  qodef-navigation--inside      qodef-navigation--hover-move\" data-options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerView&quot;:&quot;1&quot;,&quot;spaceBetween&quot;:30,&quot;spaceBetweenTablet&quot;:30,&quot;spaceBetweenMobile&quot;:30,&quot;effect&quot;:&quot;slide&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;centeredSlides&quot;:false,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;outsideNavigation&quot;:&quot;no&quot;,&quot;outsidePagination&quot;:&quot;no&quot;,&quot;unique&quot;:442,&quot;partialValue&quot;:0,&quot;disablePartialValue&quot;:&quot;&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6288.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6288.jpg 640w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6288-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6290.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6290.jpg 640w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6290-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6289.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/IMG_6291.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-3.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-3-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-2.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-2-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-1.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-1-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.37-AM-1-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.10-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.10-AM.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.10-AM-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-2.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-2-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-2-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.08-AM-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-1.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-1-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-1-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-2.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-2-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.09-AM-2-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-3.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-3-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-2.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-2-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-2-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-1.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-1-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.07-AM-1-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.06-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.06-AM.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.06-AM-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.06-AM-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.06-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.06-AM-1.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.06-AM-1-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-1024x768.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-2.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.05-AM-2-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-1.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-1-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.04-AM-1-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-5.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-5.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-5-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-5-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-4.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-4.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-4-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-4-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-3.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-3-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-3-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-2.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-2-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-2-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-1.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-1-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.14.01-AM-1-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-4.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-4.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-4-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-4-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-3.jpeg 720w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-3-169x300.jpeg 169w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-3-576x1024.jpeg 576w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-2.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-2-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-2-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-1.jpeg 720w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-1-169x300.jpeg 169w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.54-AM-1-576x1024.jpeg 576w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM-1.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM-1-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.53-AM-1-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM-300x169.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM-1024x576.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM-768x432.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM-1.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM-1-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.42-AM-1-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"648\" height=\"1152\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM.jpeg 648w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-169x300.jpeg 169w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-576x1024.jpeg 576w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-3.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-3-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-3-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-2.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-2-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-2-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"648\" height=\"1152\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-1.jpeg 648w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-1-169x300.jpeg 169w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.41-AM-1-576x1024.jpeg 576w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"648\" height=\"1152\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM.jpeg 648w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-169x300.jpeg 169w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-576x1024.jpeg 576w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1152\" height=\"648\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-2.jpeg 1152w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-2-300x169.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-2-1024x576.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-2-768x432.jpeg 768w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-1.jpeg 960w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-1-225x300.jpeg 225w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.40-AM-1-768x1024.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"648\" height=\"1152\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.39-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.39-AM.jpeg 648w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.39-AM-169x300.jpeg 169w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.39-AM-576x1024.jpeg 576w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1152\" height=\"648\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.36-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.36-AM.jpeg 1152w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.36-AM-300x169.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.36-AM-1024x576.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.36-AM-768x432.jpeg 768w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"648\" height=\"1152\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.34-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.34-AM.jpeg 648w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.34-AM-169x300.jpeg 169w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-11.07.34-AM-576x1024.jpeg 576w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-1.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-1-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-1-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.52-AM-1-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-4.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-4.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-4-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-4-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-4-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-3.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-3-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-3-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-3-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-2.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-2-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-2-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-2-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-1.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-1-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-1-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.51-AM-1-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-2.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-2-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-2-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-2-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-1.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-1-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-1-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.50-AM-1-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-2.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-2-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-2-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.49-AM-2-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-2-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-1.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-1-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-1-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.48-AM-1-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM.jpeg 1280w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-300x199.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-1024x680.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-768x510.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-2.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-2-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-2-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.47-AM-2-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"1280\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-1.jpeg 850w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-1-199x300.jpeg 199w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-1-680x1024.jpeg 680w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-23-at-10.53.45-AM-1-768x1157.jpeg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-12.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-12.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-12-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-12-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-4.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-4.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-4-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-3-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-3-1.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-3-1-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-3-1-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-6-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-6-1.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-6-1-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-8.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-8.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-8-300x169.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-8-768x432.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-9.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-9.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-9-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\t<\/div>\n\t\t<div class=\"swiper-button-prev\"><i aria-hidden=\"true\" class=\"fas fa-arrow-circle-left\"><\/i><\/div>\n\t<div class=\"swiper-button-next\"><i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7bfbe3f\" data-id=\"7bfbe3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b855a0d elementor-widget elementor-widget-image\" data-id=\"b855a0d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T122747.710.png\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T122747.710.png\" class=\"attachment-large size-large wp-image-935\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T122747.710.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T122747.710-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94539ea elementor-widget elementor-widget-image\" data-id=\"94539ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T123819.771.png\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T123819.771.png\" class=\"attachment-large size-large wp-image-936\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T123819.771.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T123819.771-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6de899a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6de899a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c546023\" data-id=\"c546023\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a84df2 elementor-widget elementor-widget-heading\" data-id=\"3a84df2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wardrobe<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c39c74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c39c74\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7003ac2\" data-id=\"7003ac2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72b230b elementor-widget elementor-widget-qi_addons_for_elementor_image_slider\" data-id=\"72b230b\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-image-slider     qodef-col-num--1 qodef-qi-grid qodef-qi-swiper-container  qodef-navigation--inside      qodef-navigation--hover-move\" data-options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerView&quot;:&quot;1&quot;,&quot;spaceBetween&quot;:30,&quot;spaceBetweenTablet&quot;:30,&quot;spaceBetweenMobile&quot;:30,&quot;effect&quot;:&quot;slide&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;centeredSlides&quot;:false,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;outsideNavigation&quot;:&quot;no&quot;,&quot;outsidePagination&quot;:&quot;no&quot;,&quot;unique&quot;:406,&quot;partialValue&quot;:0,&quot;disablePartialValue&quot;:&quot;&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-11.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-11.jpeg 1024w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-11-300x225.jpeg 300w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Ramesh-Thanjavur-11-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM-2.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM-2-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM-1.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM-1-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM.jpeg 768w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2022-08-06-at-4.43.28-PM-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/106.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/106.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/106-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/96.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/96.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/96-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/79.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/79.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/79-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/42-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/42-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/42-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/36-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/36-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/36-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/19-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/19-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/19-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/7-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/7-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/7-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/4-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/4-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/4-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/1-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/109.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/109.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/109-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/108.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/108.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/108-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/107.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/107.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/107-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/99-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/99-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/99-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/97.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/97.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/97-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/94.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/94.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/94-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/92.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/92.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/92-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/91.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/91.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/91-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/90.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/90.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/90-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/85.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/85.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/85-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/83.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/83.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/83-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/81.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/81.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/81-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/76.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/76.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/76-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/75.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/75.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/75-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/68.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/68.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/68-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/67.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/67.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/67-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/60.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/60.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/60-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/59.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/59.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/59-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/57.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/57.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/57-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/53.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/53.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/53-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/51.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/51.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/51-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/47-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/47-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/47-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/44-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/44-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/44-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/43-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/43-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/43-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/39-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/39-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/39-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/38-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/38-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/38-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/35-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/35-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/35-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/30-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/30-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/30-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/25-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/25-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/25-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/20-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/20-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/20-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/18-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/18-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/18-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/16-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/15-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/15-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/15-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/14-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/14-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/14-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/11-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/9-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/8-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/8-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/8-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/3-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/3-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/3-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/105.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/105.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/105-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/104.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/104.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/104-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/103.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/103.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/103-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/102.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/102.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/102-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/101.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/101.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/101-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/100.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/100.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/100-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/98.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/98.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/98-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/95.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/95.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/95-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/93.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/93.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/93-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/88-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/88-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/88-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/87.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/87.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/87-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/84.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/84.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/84-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/80.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/80.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/80-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/73.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/73.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/73-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/72.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/72.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/72-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/70.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/70.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/70-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/66-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/66-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/66-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/64.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/64.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/64-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/63.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/63.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/63-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/62.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/62.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/62-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/61.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/61.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/61-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/54.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/54.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/54-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/50.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/50.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/50-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/49.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/49.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/49-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/48.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/48.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/48-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/41-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/41-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/41-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/40-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/40-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/40-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/37-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/37-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/37-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/34-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/34-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/34-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/33-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/33-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/33-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/32-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/32-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/32-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/29-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/29-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/29-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/28-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/28-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/28-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/26-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/26-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/26-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/24-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/24-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/24-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/17-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/17-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/17-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/13-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/13-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/13-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/10-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/2-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/2-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/2-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/89.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/89.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/89-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/86.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/86.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/86-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/82.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/82.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/82-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/78.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/78.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/78-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/77-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/77-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/77-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/74.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/74.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/74-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/71.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/71.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/71-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/69.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/69.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/69-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/65.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/65.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/65-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/58.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/58.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/58-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/56.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/56.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/56-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/55-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/55-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/55-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/52.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/52.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/52-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/46-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/46-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/46-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/45-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/45-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/45-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/31-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/31-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/31-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/27-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/27-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/27-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/23-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/23-1.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/23-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/22-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/22-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/22-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/21-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/21-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/21-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/12-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/12-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/12-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/6-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/6-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/6-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/5-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/5-2.jpg 500w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/5-2-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\t<\/div>\n\t\t<div class=\"swiper-button-prev\"><i aria-hidden=\"true\" class=\"fas fa-arrow-circle-left\"><\/i><\/div>\n\t<div class=\"swiper-button-next\"><i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0a69a41\" data-id=\"0a69a41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c6698a elementor-widget elementor-widget-image\" data-id=\"2c6698a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130250.820.png\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130250.820.png\" class=\"attachment-large size-large wp-image-1107\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130250.820.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130250.820-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a2d81 elementor-widget elementor-widget-image\" data-id=\"29a2d81\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130118.834.png\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130118.834.png\" class=\"attachment-large size-large wp-image-1108\" alt=\"\" srcset=\"https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130118.834.png 400w, https:\/\/woodsworthindustries.com\/wp-content\/uploads\/2023\/06\/Untitled-design-2023-06-05T130118.834-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Modular Kitchen Modular Unit Wardrobe<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-162","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/pages\/162"}],"collection":[{"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/comments?post=162"}],"version-history":[{"count":68,"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/pages\/162\/revisions"}],"predecessor-version":[{"id":1344,"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/pages\/162\/revisions\/1344"}],"wp:attachment":[{"href":"https:\/\/woodsworthindustries.com\/index.php\/wp-json\/wp\/v2\/media?parent=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}